{"id":14925,"date":"2023-08-08T15:15:07","date_gmt":"2023-08-08T21:15:07","guid":{"rendered":"https:\/\/artesaniasdemexico.com\/?post_type=product&#038;p=14925"},"modified":"2026-05-23T22:55:35","modified_gmt":"2026-05-24T04:55:35","slug":"muwieri-arte-huichol-24021","status":"publish","type":"product","link":"https:\/\/artesaniasdemexico.com\/pt\/produto\/muwieri-arte-huichol-24021\/","title":{"rendered":"Muwieri | Arte Huichol"},"content":{"rendered":"<p><strong>Pessoal de comando - Muwieri Huichol<\/strong><\/p>\n<p style=\"text-align: justify;\">O \"bast\u00e3o de comando\" na cultura Huichol, conhecido como \"muwieri ou tatei kie\", \u00e9 um objeto de grande import\u00e2ncia e simbolismo. Os Huichol s\u00e3o um povo ind\u00edgena do M\u00e9xico, especialmente conhecido pela sua arte e espiritualidade enraizada na natureza.<\/p>\n<p style=\"text-align: justify;\">O bast\u00e3o de comando, neste contexto, \u00e9 um s\u00edmbolo de autoridade e lideran\u00e7a no seio da comunidade Huichol. \u00c9 geralmente esculpido \u00e0 m\u00e3o e decorado com elementos representativos da vis\u00e3o do mundo e da espiritualidade Huichol, tais como desenhos geom\u00e9tricos, figuras de animais sagrados e elementos naturais.<\/p>\n<p style=\"text-align: justify;\">Este bast\u00e3o de comando \u00e9 utilizado durante cerim\u00f3nias e rituais importantes, e o seu portador \u00e9 geralmente uma figura de autoridade ou um l\u00edder da comunidade, como um xam\u00e3 ou um l\u00edder espiritual. A sua presen\u00e7a e manuseamento fazem parte integrante das pr\u00e1ticas culturais e religiosas Huichol.<\/p>\n<p style=\"text-align: justify;\">\u00c9 importante notar que os conhecimentos sobre a cultura Huichol podem variar e evoluir com o tempo, pelo que recomendo que consulte fontes adicionais e actualizadas para obter informa\u00e7\u00f5es mais completas e precisas.<\/p>","protected":false},"excerpt":{"rendered":"<p>Muwieri ou bast\u00e3o Huichol feito com penas e fios pelos Huichols de Nayarit, M\u00e9xico.<\/p>","protected":false},"featured_media":14876,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[16,132,404],"product_tag":[405],"class_list":["post-14925","product","type-product","status-publish","has-post-thumbnail","product_cat-arte-huichol","product_cat-joyeria-y-accesorios","product_cat-muwieri","product_tag-ah-muwieri","first","outofstock","purchasable","product-type-simple"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/artesaniasdemexico.com\/pt\/wp-json\/wp\/v2\/product\/14925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artesaniasdemexico.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/artesaniasdemexico.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/artesaniasdemexico.com\/pt\/wp-json\/wp\/v2\/comments?post=14925"}],"version-history":[{"count":0,"href":"https:\/\/artesaniasdemexico.com\/pt\/wp-json\/wp\/v2\/product\/14925\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/artesaniasdemexico.com\/pt\/wp-json\/wp\/v2\/media\/14876"}],"wp:attachment":[{"href":"https:\/\/artesaniasdemexico.com\/pt\/wp-json\/wp\/v2\/media?parent=14925"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/artesaniasdemexico.com\/pt\/wp-json\/wp\/v2\/product_brand?post=14925"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/artesaniasdemexico.com\/pt\/wp-json\/wp\/v2\/product_cat?post=14925"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/artesaniasdemexico.com\/pt\/wp-json\/wp\/v2\/product_tag?post=14925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}